{"id":1537,"date":"2023-12-06T12:46:54","date_gmt":"2023-12-06T12:46:54","guid":{"rendered":"https:\/\/alcaidesa.property\/servicios\/"},"modified":"2024-08-12T17:00:44","modified_gmt":"2024-08-12T17:00:44","slug":"servicios","status":"publish","type":"page","link":"https:\/\/alcaidesa.property\/es\/servicios\/","title":{"rendered":"Servicios"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbmde-vertical-align\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(18,132,209,0.8) 0%|rgba(18,132,209,0.4) 100%\u00bb background_image=\u00bbhttps:\/\/alcaidesa.property\/wp-content\/uploads\/2024\/02\/avi-werde-hHz4yrvxwlA-unsplash.jpg\u00bb background_enable_image=\u00bbon\u00bb min_height=\u00bb435px\u00bb custom_margin=\u00bb-155px||||false|false\u00bb custom_padding=\u00bb220px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_font_size=\u00bb18px\u00bb header_text_align=\u00bbcenter\u00bb header_font_size=\u00bb50px\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb30px\u00bb header_2_line_height=\u00bb1.6em\u00bb header_3_font=\u00bb|||on|||||\u00bb header_3_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bb#007EC7&#8243; header_3_font_size=\u00bb26px\u00bb header_3_line_height=\u00bb1.6em\u00bb text_orientation=\u00bbjustified\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb||0px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Servicios<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|700||on|||||\u00bb header_2_text_color=\u00bb#095182&#8243; header_2_font_size=\u00bb36px\u00bb header_3_font=\u00bb|||on|||||\u00bb header_3_text_color=\u00bb#878D91&#8243; header_3_font_size=\u00bb26px\u00bb header_3_line_height=\u00bb1.6em\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>SERVICIOS DE ALQUILER Y GESTI\u00d3N INMOBILIARIA<\/h2>\n<p>  \u00a1Transforma tu experiencia inmobiliaria con nosotros! No s\u00f3lo le ayudamos a comprar y vender la propiedad de sus sue\u00f1os, sino que tambi\u00e9n le ofrecemos soluciones personalizadas de gesti\u00f3n inmobiliaria. Desde la custodia de llaves hasta la asistencia en el arrendamiento, pasando por el mantenimiento de la piscina, nuestros servicios est\u00e1n dise\u00f1ados teniendo en cuenta sus necesidades espec\u00edficas. Como su socio de confianza en la gesti\u00f3n inmobiliaria, estamos a su lado en todo momento. \u00bfListo para sumergirse en la soleada tranquilidad de la vida espa\u00f1ola al tiempo que se beneficia de una inversi\u00f3n inmobiliaria? Quiz\u00e1s est\u00e9 pensando en pasar sus vacaciones en su propiedad espa\u00f1ola y alquilarla a otros veraneantes durante el resto del a\u00f1o. La ejecuci\u00f3n perfecta de este plan puede resultar desalentadora, sobre todo si vives en el extranjero o te enfrentas a barreras ling\u00fc\u00edsticas. Ofrecemos servicios de gesti\u00f3n inmobiliaria a medida para solucionar precisamente eso, dando a su propiedad el trato VIP que se merece, tanto si la ha comprado con nosotros como si no. Con nosotros, su propiedad nunca est\u00e1 sola, aunque usted est\u00e9 a kil\u00f3metros de distancia. Nuestro equipo de experimentados profesionales cuenta con una trayectoria inigualable de 20 a\u00f1os en el alquiler y gesti\u00f3n de inmuebles en Alcaidesa. Adaptamos nuestros servicios a su situaci\u00f3n particular, garantizando que su propiedad alcance su m\u00e1ximo potencial mientras est\u00e9 bajo nuestro cuidado. Nos encargamos de todas las tareas de gesti\u00f3n inmobiliaria, desde responder a las formalidades locales hasta comercializar tu propiedad para que tenga una visibilidad \u00f3ptima. <strong>Libera el potencial de alquiler de tu propiedad con nosotros &#8211; haz clic <a href=\"https:\/\/alcaidesa.property\/es\/alquile-su-propiedad\/\">aqu\u00ed<\/a> para m\u00e1s informaci\u00f3n.<\/strong>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbMantenimiento de llaves\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf084;||fa||900&#8243; image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#007EC7&#8243; header_font_size=\u00bb28px\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbjustify\u00bb body_line_height=\u00bb1.4em\u00bb image_icon_custom_margin=\u00bb|15px|||false|false\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]Guardamos de forma segura las llaves de su propiedad, poni\u00e9ndolas a disposici\u00f3n de los propietarios, invitados o comerciantes que las soliciten.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbGesti\u00f3n de la propiedad\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf560;||fa||900&#8243; image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#007EC7&#8243; header_font_size=\u00bb28px\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbjustify\u00bb body_line_height=\u00bb1.4em\u00bb image_icon_custom_margin=\u00bb|15px|||false|false\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]Nuestros servicios combinan la custodia de llaves y las revisiones quincenales de la propiedad para detectar r\u00e1pidamente los problemas de mantenimiento.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbServicios para hu\u00e9spedes\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf562;||fa||900&#8243; image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#007EC7&#8243; header_font_size=\u00bb28px\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbjustify\u00bb body_line_height=\u00bb1.4em\u00bb image_icon_custom_margin=\u00bb|15px|||false|false\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb] Garantizamos un servicio personal de \u00abbienvenida\u00bb a los hu\u00e9spedes que llegan y nos encargamos de los recados esenciales.[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbLimpieza y lavander\u00eda\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe06e;||fa||900&#8243; image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#007EC7&#8243; header_font_size=\u00bb28px\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbjustify\u00bb body_line_height=\u00bb1.4em\u00bb image_icon_custom_margin=\u00bb|15px|||false|false\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]Preparamos su propiedad para cada llegada garantizando la limpieza y ropa de cama fresca, para que usted o sus invitados puedan disfrutar de un ambiente acogedor.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbSoluci\u00f3n de problemas\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf590;||fa||900&#8243; image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#007EC7&#8243; header_font_size=\u00bb28px\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbjustify\u00bb body_line_height=\u00bb1.4em\u00bb image_icon_custom_margin=\u00bb|15px|||false|false\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]Proporcionamos soluciones r\u00e1pidas a todos los problemas importantes de la propiedad, coordinando con t\u00e9cnicos cualificados las reparaciones necesarias.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbServicios postales y de reparto\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf48b;||fa||900&#8243; image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#007EC7&#8243; header_font_size=\u00bb28px\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbjustify\u00bb body_line_height=\u00bb1.4em\u00bb image_icon_custom_margin=\u00bb|15px|||false|false\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Nos encargamos de la recogida y el reenv\u00edo del correo, seg\u00fan sea necesario.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbServicios adicionales\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf067;||fa||900&#8243; image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bb#007EC7&#8243; header_font_size=\u00bb28px\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbjustify\u00bb body_line_height=\u00bb1.4em\u00bb image_icon_custom_margin=\u00bb|15px|||false|false\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]Nos encargamos de los servicios de jardineros y mantenimiento de piscinas, pagos de facturas de servicios p\u00fablicos, tramitaci\u00f3n de declaraciones de impuestos personales e IBI anual (Impuestos sobre la Vivienda del Ayuntamiento).[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#E6E6E6&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbOpen Sans||||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|700||on|||||\u00bb header_2_text_color=\u00bb#095182&#8243; header_2_font_size=\u00bb36px\u00bb header_3_font=\u00bb|||on|||||\u00bb header_3_text_color=\u00bb#878D91&#8243; header_3_font_size=\u00bb26px\u00bb header_3_line_height=\u00bb1.6em\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>SU PROPIEDAD, NUESTRA PRIORIDAD.<\/h2>\n<p>  Ponte en contacto con nosotros hoy mismo para conocer nuestros paquetes, servicios y tarifas de gesti\u00f3n inmobiliaria.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ServiciosSERVICIOS DE ALQUILER Y GESTI\u00d3N INMOBILIARIA \u00a1Transforma tu experiencia inmobiliaria con nosotros! No s\u00f3lo le ayudamos a comprar y vender la propiedad de sus sue\u00f1os, sino que tambi\u00e9n le ofrecemos soluciones personalizadas de gesti\u00f3n inmobiliaria. Desde la custodia de llaves hasta la asistencia en el arrendamiento, pasando por el mantenimiento de la piscina, nuestros servicios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":343,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"class_list":["post-1537","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/pages\/1537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/comments?post=1537"}],"version-history":[{"count":13,"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/pages\/1537\/revisions"}],"predecessor-version":[{"id":2887,"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/pages\/1537\/revisions\/2887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/media\/343"}],"wp:attachment":[{"href":"https:\/\/alcaidesa.property\/es\/wp-json\/wp\/v2\/media?parent=1537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}